{"id":3459,"date":"2023-02-28T12:40:47","date_gmt":"2023-02-28T12:40:47","guid":{"rendered":"https:\/\/basspirit.com\/?p=3459"},"modified":"2023-02-28T12:49:11","modified_gmt":"2023-02-28T12:49:11","slug":"entrevista-a-alexandre-laeddis","status":"publish","type":"post","link":"https:\/\/basspirit.com\/es\/2023\/02\/28\/entrevista-a-alexandre-laeddis\/","title":{"rendered":"Entrevista a Alexandre Laeddis"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3459\" class=\"elementor elementor-3459\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56ef03a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56ef03a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1bb3917b\" data-id=\"1bb3917b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22b08f9d elementor-widget elementor-widget-text-editor\" data-id=\"22b08f9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span style=\"font-size: 18pt;\">Entrevista a Alexandre Laeddis<\/span><\/h1><p>Hablamos con Alexandre Laeddis, productor y dj de <a href=\"https:\/\/basspirit.com\/2023\/02\/20\/recopilatorio-club-h-v-i-1999-harry-the-bastard\/\">vinilos<\/a> de Barcelona. En cada uno de sus sets se puede apreciar una progresi\u00f3n procedente del Techno, principalmente de discos entre 1998 y 2005 editados en sellos de Inglaterra, Suecia o Alemania.<\/p><p>\u00a0<\/p><p>Seg\u00fan nos cuenta con una amplia trayectoria, pues ha tenido la ocasi\u00f3n de poder actuar en el Anomalie de Berlin con Room Trax, H\u00f6r Berlin, Razzmatazz de Barcelona, Radion de \u00c1msterdam con Antidote, Gare de Porto con Phase.ctv, Exil de Zurich, Dabadaba de Donosti y en su pol\u00edgono favorito el cual considera su casa en Madrid con Utop\u00eda Society y con Phase.ctv, colectivo en el que es residente.<\/p><p>\u00a0<\/p><p><div class=\"jetpack-video-wrapper\"><iframe title=\"Front Left - Alexandre Laeddis \/ July 27 \/ 8pm-9pm\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/TIv1OIhSQ-M?start=743&feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/p><p>\u00a0<\/p><p><strong>\u00bfDe d\u00f3nde te nace esa predilecci\u00f3n por la electr\u00f3nica?<\/strong><\/p><p>\u00a0<\/p><p>Conozco la m\u00fasica electr\u00f3nica desde el 2008, pero me enamor\u00e9 de ella en 2019 en mi primera visita a Berghain. Vi que esa es la manera y el lugar de y para esa m\u00fasica. Es un c\u00edrculo perfecto. Ah\u00ed tiene todo el sentido y de esa manera. Todo lo dem\u00e1s son aproximaciones, algunas muy reales y que transmiten sensaciones muy parecidas, pero es solo ah\u00ed lo que tiene que ser.<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><strong>\u00bfC\u00f3mo definir\u00edas tus producciones? \u00bfQu\u00e9 elementos la componen, cu\u00e1les destacar\u00edas? \u00bfCuentas con otros aka\u00b4s para producciones de otro g\u00e9nero?<\/strong><\/p><p>\u00a0<\/p><p>Mis producciones las definir\u00eda como herramientas para el\/la dj. No es m\u00fasica para escuchar en casa o con auriculares, es m\u00fasica hecha para la pista de baile.<\/p><p>\u00a0<\/p><p><strong><em>\u201cCada producci\u00f3n est\u00e1 compuesta por los m\u00ednimos elementos. Directos, crudos y frescos. 909, un sinte y ya\u201d<\/em><\/strong><\/p><p>\u00a0<\/p><p>Desde dentro es dif\u00edcil ver si mi esencia o mi marca personal est\u00e1 en mis <a href=\"https:\/\/basspirit.com\/2023\/02\/20\/recopilatorio-club-h-v-i-1999-harry-the-bastard\/\">producciones<\/a>, pero alguna vez que he preguntado a mis amigos productores cercanos me han dicho que s\u00ed se puede apreciar.<\/p><p>\u00a0<\/p><p>De momento no tengo un aka para otro g\u00e9nero aunque no lo descarto. Aun as\u00ed, me gusta demasiado el <a href=\"https:\/\/soundcloud.com\/ox-techne\">Techno<\/a> 4&#215;4 y dudo que salga de ah\u00ed.<\/p><p>\u00a0<\/p><p><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"3465\" data-permalink=\"https:\/\/basspirit.com\/es\/whatsapp-image-2023-02-28-at-13-21-00\/\" data-orig-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00.jpeg?fit=1080%2C1193&amp;ssl=1\" data-orig-size=\"1080,1193\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Soundit Barcelona\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00.jpeg?fit=640%2C707&amp;ssl=1\" data-recalc-dims=\"1\" class=\" wp-image-3465 aligncenter\" src=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00-272x300.jpeg?resize=505%2C557&#038;ssl=1\" alt=\"fotograf\u00eda de Alexandre Laeddis\" width=\"505\" height=\"557\" srcset=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00.jpeg?resize=272%2C300&amp;ssl=1 272w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00.jpeg?resize=927%2C1024&amp;ssl=1 927w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00.jpeg?resize=768%2C848&amp;ssl=1 768w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00.jpeg?resize=480%2C530&amp;ssl=1 480w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00.jpeg?w=1080&amp;ssl=1 1080w\" sizes=\"(max-width: 505px) 100vw, 505px\" \/><\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><b>\u00bfQu\u00e9 nos puedes contar acerca de tu sello Hemisferio Records? \u00bfQu\u00e9 artistas han podido lanzar m\u00fasica en el mismo? \u00bfCon qu\u00e9 proyecci\u00f3n cuenta tu sello?<\/b><\/p><p>\u00a0<\/p><p>Hemisferio Records se fund\u00f3, principalmente, para sacar m\u00fasica realizada por m\u00ed. No ten\u00eda ni idea de nada en ese momento, solo quer\u00eda sacar m\u00fasica bajo un sello para no sacarla tal en la nada.<\/p><p>\u00a0<\/p><p>El label est\u00e1 enfocado en m\u00fasica para la pista. En Hemisferio han sacado m\u00fasica desde amigos como Judy, Not A Headliner y R-010, a figuras que actualmente representan el presente y futuro del Techno como Decoder, NYCO o Nicolas Vogler.<\/p><p>\u00a0<\/p><p>Hace unos d\u00edas se lanz\u00f3 en Hemisferio un EP de R-010, amigo y productor de Madrid.\u00a0<\/p><p>\u00a0<\/p><p><iframe title=\"HEMISFERIO 14 - R-010 by Hemisferio Records\" width=\"640\" height=\"450\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?visual=true&url=https%3A%2F%2Fapi.soundcloud.com%2Fplaylists%2F1574561011&show_artwork=true&maxheight=960&maxwidth=640\"><\/iframe><\/p><p>\u00a0<\/p><p>En cuanto a la proyecci\u00f3n del sello, quiero cambiar de direcci\u00f3n y sacar m\u00fasica solo en formato vinilo.<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><strong>\u00bfHas lanzado ya m\u00fasica en vinilo? \u00bfCu\u00e1les son para ti tus mejores producciones? \u00bfHas realizado alguna colaboraci\u00f3n con alg\u00fan artista?<\/strong><\/p><p>\u00a0<\/p><p>Mi primer vinilo es una colaboraci\u00f3n con Judy que saldr\u00e1 este a\u00f1o. Es un release conjunto de Phase.ctv con Heist Mode.<\/p><p>\u00a0<\/p><p>Todas mis producciones (y todas las producciones) tienen algo que las hacer ser mejor.<\/p><p>\u00a0<\/p><p>\u201cSiempre habr\u00e1 un momento y un lugar determinado para que alguien haga sonar ese tema y sea sublime\u201d<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><strong>\u00bfQu\u00e9 sellos y artistas han sido para ti de gran inspiraci\u00f3n? \u00bfCu\u00e1l es tu track favorito?<\/strong><\/p><p>\u00a0<\/p><p>Mis influencias a nivel producci\u00f3n son The Advent, Stigmata, Jeff Mills, Stef Mendesidis y sellos como Primate, MB Elektronics, Sino, Conform, Proper NYC, Phont Music y muchos m\u00e1s.<\/p><p>\u00a0<\/p><p>A nivel dj, \u00c1ngel Molina, \u00d3scar Mulero, Jeff Mills, Freddy K, Dj Frequency y Laure Croft.<\/p><p>\u00a0<\/p><p>Mi track favorito podr\u00eda decirse que es <strong>Technasia \u2013 Evergreen III\u00a0<\/strong><\/p><p>\u00a0<\/p><p><div class=\"jetpack-video-wrapper\"><iframe title=\"Technasia - Evergreen III\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/ibAH_MyOL_g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><b>Por curiosidad, \u00bfcon qu\u00e9 otros g\u00e9neros musicales (fuera de la electr\u00f3nica) disfrutas? \u00bfQu\u00e9 canci\u00f3n o canciones podr\u00edas destacar?<\/b><\/p><p>\u00a0<\/p><p>A parte de la electr\u00f3nica, disfruto de la m\u00fasica cl\u00e1sica, algo de disco, funk y artistas o grupos como Alaska, Miguel Bos\u00e9, Mecano y Joan Manuel Serrat.<\/p><p>\u00a0<\/p><p>Canciones a destacar\u2026.\u201dMediterr\u00e1neo\u201d de Joan Manuel Serrat y cualquier tema de Sade. Es inmediato el sentimiento que me genera. Es algo entre admiraci\u00f3n, placer y bienestar. Es la m\u00fasica que escuchaba en verano de peque\u00f1o de vacaciones con mis padres.<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><strong>\u00bfPuedes contar alg\u00fan avance de tus pr\u00f3ximas actuaciones?<\/strong><\/p><p>\u00a0<\/p><p>Pr\u00f3ximamente estar\u00e9 rompiendo la pista en el <a href=\"https:\/\/www.soundit.es\">Soundit en Barcelona<\/a><\/p><p>\u00a0<\/p><p>Para seguir m\u00e1s de cerca a este artistazo, pod\u00e9is hacerlo a trav\u00e9s de <strong><a href=\"https:\/\/www.instagram.com\/alexandrelaeddis\/\">Instagram \u2013 Alexandre Laeddis (@alexandrelaeddis)<\/a><\/strong><\/p><p>\u00a0<\/p><p>Para que tu d\u00eda no sea tan perturbador, dale al play al set de Laeddis\u2026Ver\u00e1s que todo ser\u00e1 mucho m\u00e1s esclarecedor \ud83d\ude42<\/p><p>\u00a0<\/p><p><iframe title=\"FrenzyPodcast #136 - Alexandre Laeddis by Frenzy\" width=\"640\" height=\"400\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?visual=true&url=https%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F1401771991&show_artwork=true&maxheight=960&maxwidth=640\"><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59d56bbc elementor-widget elementor-widget-text-editor\" data-id=\"59d56bbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>#basspiritmagazine\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6add8632\" data-id=\"6add8632\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-37f7abba\" data-id=\"37f7abba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b0e17df elementor-widget elementor-widget-spacer\" data-id=\"6b0e17df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-160030fb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"160030fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42005b5e elementor-widget elementor-widget-text-editor\" data-id=\"42005b5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cambiando la t\u00f3nica de comunicar por un Gin tonic.<\/p><p>\u00a0<\/p><p>Te invitamos a que nos visites en Instagram y si te gusta lo que ves&#8230;\u00a0\u00a0<\/p><p><strong>\u00a1 S\u00cdGUENOS !<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10caba7f elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"10caba7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-34b2cf4\" href=\"https:\/\/www.instagram.com\/basspiritmag\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22928761 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"22928761\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dff4b29 elementor-widget elementor-widget-spacer\" data-id=\"dff4b29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34b7db18 elementor-widget elementor-widget-text-editor\" data-id=\"34b7db18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" data-attachment-id=\"892\" data-permalink=\"https:\/\/basspirit.com\/es\/music-speaks\/\" data-orig-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2020\/05\/music-speaks.png?fit=600%2C600&amp;ssl=1\" data-orig-size=\"600,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"music speaks\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2020\/05\/music-speaks.png?fit=600%2C600&amp;ssl=1\" data-recalc-dims=\"1\" class=\"alignnone size-medium wp-image-892\" src=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2020\/05\/music-speaks-300x300.png?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2020\/05\/music-speaks.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2020\/05\/music-speaks.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2020\/05\/music-speaks.png?resize=480%2C480&amp;ssl=1 480w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2020\/05\/music-speaks.png?w=600&amp;ssl=1 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>\u00a0<\/p><p><iframe title=\"Spotify Embed: Basspirit Radio \" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/playlist\/4eG44xfbSTmSCQ2XkmtK5s?utm_source=oembed\"><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1986c105 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1986c105\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a14e0a6\" data-id=\"1a14e0a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hablamos con Alexandre Laeddis, productor y dj de vinilos de Barcelona. En cada uno de sus sets se puede apreciar una progresi\u00f3n procedente del Techno, principalmente de discos entre 1998 y 2005 editados en sellos de Inglaterra, Suecia o Alemania<\/p>\n","protected":false},"author":1,"featured_media":3465,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,11],"tags":[],"class_list":["post-3459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basspiritmagazine","category-entrevistas"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-02-28-at-13.21.00.jpeg?fit=1080%2C1193&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pbSsRh-TN","jetpack-related-posts":[{"id":3092,"url":"https:\/\/basspirit.com\/es\/2022\/07\/22\/phase-ctv-x-balls-baile-viernes-8-julio-2022\/","url_meta":{"origin":3459,"position":0},"title":"PHASE Ctv x Balls Baile @ Secret Location &#8211; Madrid, viernes 8 julio 2022","author":"Paquitaplatos","date":"22 julio 2022","format":false,"excerpt":"El colectivo de m\u00fasica electr\u00f3nica afincado en Madrid, Phase Ctv y Balls Baile (M\u00fanich) unieron fuerzas para dar cierre a la temporada","rel":"","context":"En \u00abart\u00edculos\u00bb","block_context":{"text":"art\u00edculos","link":"https:\/\/basspirit.com\/es\/category\/articulos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2022\/07\/phase-ctv.png?fit=530%2C530&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2022\/07\/phase-ctv.png?fit=530%2C530&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2022\/07\/phase-ctv.png?fit=530%2C530&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":3523,"url":"https:\/\/basspirit.com\/es\/2023\/03\/15\/vinyl-vandals-phase-ctv-madrid-18-marzo\/","url_meta":{"origin":3459,"position":1},"title":"Vinyl Vandals por Phase.Ctv este s\u00e1bado 18 de marzo en Madrid","author":"Paquitaplatos","date":"15 marzo 2023","format":false,"excerpt":"El colectivo madrile\u00f1o Phase.Ctv organiza en su campamento base de Vallecas una noche solo a vinilo \u00a13 horas por set! Espectacular documento.","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"cartel evento m\u00fasica electr\u00f3nica a vinilo","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-17.05.34.jpeg?fit=1061%2C1071&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-17.05.34.jpeg?fit=1061%2C1071&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-17.05.34.jpeg?fit=1061%2C1071&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-17.05.34.jpeg?fit=1061%2C1071&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-17.05.34.jpeg?fit=1061%2C1071&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4853,"url":"https:\/\/basspirit.com\/es\/2024\/04\/11\/gomorra-presenta-truncate-the-locals-viernes-12-de-abril\/","url_meta":{"origin":3459,"position":2},"title":"Gomorra presenta: TRUNCATE &#038; THE LOCALS &#8211; Viernes 12 de abril","author":"Paquitaplatos","date":"11 abril 2024","format":false,"excerpt":"Gomorra se complace en anunciar uno de los eventos m\u00e1s esperados de la temporada: TRUNCATE & THE LOCALS","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"flyer evento truncate","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/04\/truncate-1.png?fit=1080%2C1080&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/04\/truncate-1.png?fit=1080%2C1080&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/04\/truncate-1.png?fit=1080%2C1080&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/04\/truncate-1.png?fit=1080%2C1080&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/04\/truncate-1.png?fit=1080%2C1080&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3605,"url":"https:\/\/basspirit.com\/es\/2023\/04\/14\/entrevista-r-010-phase-ctv\/","url_meta":{"origin":3459,"position":3},"title":"Entrevista a R-010","author":"Paquitaplatos","date":"14 abril 2023","format":false,"excerpt":"Entrevista a R-010Desde Basspirit Magazine entrevistamos a R-010, Lucas Rojo, amigo de nuestra familia y un artistazo all\u00e1 donde los haya. Aunque no sea una verdad absoluta y extendida, normalmente a todo artista le atrae, en primera instancia, la idea de aprender a mezclar para, posteriormente, meterse de lleno en\u2026","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"R-010 actuando en Vortex","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/04\/imagen_2023-04-14_234700860.png?fit=601%2C733&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/04\/imagen_2023-04-14_234700860.png?fit=601%2C733&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2023\/04\/imagen_2023-04-14_234700860.png?fit=601%2C733&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":5104,"url":"https:\/\/basspirit.com\/es\/2024\/05\/15\/entrevista-a-ground9\/","url_meta":{"origin":3459,"position":4},"title":"Entrevista a GROUND9","author":"Paquitaplatos","date":"15 mayo 2024","format":false,"excerpt":"Entrevista exclusiva con GROUND9: DJ y amante del vinilo","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"aphex twin","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/05\/stage_1715736554.jpeg?fit=1080%2C1080&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/05\/stage_1715736554.jpeg?fit=1080%2C1080&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/05\/stage_1715736554.jpeg?fit=1080%2C1080&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/05\/stage_1715736554.jpeg?fit=1080%2C1080&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2024\/05\/stage_1715736554.jpeg?fit=1080%2C1080&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2255,"url":"https:\/\/basspirit.com\/es\/2021\/10\/25\/entrevista-al-productor-l_\/","url_meta":{"origin":3459,"position":5},"title":"Entrevista a ^L_","author":"Paquitaplatos","date":"25 octubre 2021","format":false,"excerpt":"^L_: \u00abHe pinchado en clubes de Berl\u00edn, Hamburgo (en el legendario Golden Pudel), Leipzig, Baviera y en Brasil\u00bb","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2021\/10\/%5EL_-1.jpg?fit=1105%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2021\/10\/%5EL_-1.jpg?fit=1105%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2021\/10\/%5EL_-1.jpg?fit=1105%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2021\/10\/%5EL_-1.jpg?fit=1105%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2021\/10\/%5EL_-1.jpg?fit=1105%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/posts\/3459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/comments?post=3459"}],"version-history":[{"count":0,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/posts\/3459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/media\/3465"}],"wp:attachment":[{"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/media?parent=3459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/categories?post=3459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/tags?post=3459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}