{"id":6652,"date":"2026-04-21T10:35:44","date_gmt":"2026-04-21T10:35:44","guid":{"rendered":"https:\/\/basspirit.com\/?p=6652"},"modified":"2026-04-23T10:43:54","modified_gmt":"2026-04-23T10:43:54","slug":"vegim-magnetopause-ep-el-arte-de-la-tension-en-el-techno-balcanico","status":"publish","type":"post","link":"https:\/\/basspirit.com\/es\/2026\/04\/21\/vegim-magnetopause-ep-el-arte-de-la-tension-en-el-techno-balcanico\/","title":{"rendered":"Vegim &#8211; Magnetopause EP: El arte de la tensi\u00f3n en el techno balc\u00e1nico"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6652\" class=\"elementor elementor-6652\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-705fb207 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"705fb207\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6975bfe3\" data-id=\"6975bfe3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9d0bb7 elementor-widget elementor-widget-text-editor\" data-id=\"f9d0bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span style=\"font-size: 28px;\">Vegim &#8211; Magnetopause EP : \u00abEl arte de la tensi\u00f3n en el techno balc\u00e1nico\u00bb<\/span><\/h1><p>En una escena saturada de f\u00f3rmulas r\u00e1pidas y drops dise\u00f1ados para el consumo ef\u00edmero, el productor kosovar afincado en Croacia, <strong>Vegim<\/strong>, juega en otra liga. Con su nuevo trabajo <strong>Magnetopause<\/strong>, lanzado el pasado <strong>26 de marzo en TMM Records<\/strong>, no hay concesiones ni atajos.<\/p><p>\u00a0<\/p><p><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"6654\" data-permalink=\"https:\/\/basspirit.com\/es\/1-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?fit=1882%2C1700&amp;ssl=1\" data-orig-size=\"1882,1700\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Vegim Magnetopause EP\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?fit=640%2C578&amp;ssl=1\" data-recalc-dims=\"1\" class=\" wp-image-6654 aligncenter\" src=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?resize=602%2C544\" alt=\"Vegim Magnetopause EP\" width=\"602\" height=\"544\" srcset=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?w=1882&amp;ssl=1 1882w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?resize=300%2C271&amp;ssl=1 300w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?resize=1024%2C925&amp;ssl=1 1024w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?resize=768%2C694&amp;ssl=1 768w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?resize=1536%2C1387&amp;ssl=1 1536w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?resize=13%2C12&amp;ssl=1 13w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?resize=480%2C434&amp;ssl=1 480w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/1.jpg?w=1280 1280w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/><\/p><p>\u00a0<\/p><p>Su <a href=\"https:\/\/basspirit.com\/es\/2026\/04\/14\/niels-orens-never-again-offc03-introspeccion-sonora-entre-alienacion-textura-y-tension-contenida\/\">identidad<\/a> se ha construido desde la crudeza que define parte del techno balc\u00e1nico contempor\u00e1neo, cercano a corrientes m\u00e1s industriales y mentales del circuito europeo. Eso se percibe desde el primer surco: una narrativa s\u00f3lida, basada en la tensi\u00f3n, el espacio y un control total del sonido. Este 12\u201d funciona como arma de club, pero tambi\u00e9n como una pieza de inmersi\u00f3n para quien busca algo m\u00e1s que funcionalidad.<\/p><h2><span style=\"font-size: 22px;\">Presi\u00f3n, espacio y el peso de la narrativa<\/span><\/h2><p>Magnetopause se mueve en una fricci\u00f3n constante, no es <a href=\"https:\/\/basspirit.com\/es\/2026\/04\/16\/prophecy-07-ingenieria-de-club-en-vinilo\/\">techno<\/a> para pasar el rato. Es una inmersi\u00f3n en la que el espacio entre los sonidos importa tanto como el golpe del bombo.<\/p><p><br \/><strong>La cara A<\/strong> inicia el descenso mental con \u201cThe Future\u201d, un paisaje de est\u00e1tica y atm\u00f3sfera donde el groove queda en segundo plano mientras una voz marca un punto de partida hacia lo desconocido. Sin romper ese hilo, \u201cMy Thoughts Are Not Facts\u201d entra y la tensi\u00f3n se vuelve f\u00edsica. Es un pulso firme y funcional. El cierre de la cara A llega con \u201cNothing Could Go Wrong\u201d, m\u00e1s abstracto y contenido, preparando el terreno para lo que viene.<\/p><p>\u00a0<\/p><p><iframe title=\"Vegim - Magnetopause EP [LTD075] by TMM Records | Alhena Records\" width=\"640\" height=\"400\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?visual=true&url=https%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F2289596276&show_artwork=true&maxheight=960&maxwidth=640\"><\/iframe><\/p><p><br \/><strong>En la cara B<\/strong>, aqu\u00ed es donde el disco muerde. El track hom\u00f3nimo, \u00abMagnetopause\u00bb, golpea con una presi\u00f3n hipn\u00f3tica y constante. \u00abDeployable Structures\u00bb es pura ingenier\u00eda de tensi\u00f3n: aprieta el pecho mientras las texturas se desplazan y desestabilizan el espacio sonoro. En \u201cLook Inside Me\u201d, la energ\u00eda se repliega hacia un plano m\u00e1s introspectivo, antes de cerrar con \u201cRendered Speechless\u201d, un final sin concesiones, que deja un eco espacial y al oyente suspendido en un pensamiento infinito.<\/p><h2><span style=\"font-size: 22px;\">Textura y control milim\u00e9trico<\/span><\/h2><p>El mastering de Boris act\u00faa como el pegamento invisible del conjunto. Hay pegada y definici\u00f3n, pero sobre todo respeto por lo original que intenta transmitir Vegim. Nada suena sobreprocesado, cada elemento encuentra su sitio sin perder car\u00e1cter. El artwork de Kobalt sigue esa misma l\u00ednea, con una est\u00e9tica sobria y futurista que refuerza la identidad del vinilo.\u00a0<\/p><p>\u00a0<\/p><p><img decoding=\"async\" data-attachment-id=\"6657\" data-permalink=\"https:\/\/basspirit.com\/es\/slide3\/\" data-orig-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/slide3.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Vegim Magnetopause EP\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/slide3.jpg?fit=500%2C500&amp;ssl=1\" data-recalc-dims=\"1\" class=\" wp-image-6657 aligncenter\" src=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/slide3.jpg?resize=579%2C579\" alt=\"Vegim Magnetopause EP\" width=\"579\" height=\"579\" srcset=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/slide3.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/slide3.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/slide3.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/slide3.jpg?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/slide3.jpg?resize=480%2C480&amp;ssl=1 480w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/><\/p><h2><span style=\"font-size: 22px;\">Un 12\u201d que no negocia su identidad<\/span><\/h2><p>Magnetopause no es inmediato ni complaciente. Es un trabajo desafiante que exige atenci\u00f3n y, a cambio, devuelve puro car\u00e1cter. Vegim no ha hecho un disco de club; ha dise\u00f1ado una experiencia de inmersi\u00f3n t\u00e9cnica que te obliga a mirar hacia dentro, y lo que hay ah\u00ed, a veces, es tan oscuro como fascinante.<\/p><p>\u00a0<\/p><p><img decoding=\"async\" data-attachment-id=\"6655\" data-permalink=\"https:\/\/basspirit.com\/es\/0043915739_10\/\" data-orig-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?fit=904%2C1200&amp;ssl=1\" data-orig-size=\"904,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Vegim Magnetopause EP\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?fit=640%2C850&amp;ssl=1\" data-recalc-dims=\"1\" class=\" wp-image-6655 aligncenter\" src=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?resize=555%2C736\" alt=\"Vegim Magnetopause EP\" width=\"555\" height=\"736\" srcset=\"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?w=904&amp;ssl=1 904w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?resize=226%2C300&amp;ssl=1 226w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?resize=771%2C1024&amp;ssl=1 771w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?resize=768%2C1019&amp;ssl=1 768w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?resize=9%2C12&amp;ssl=1 9w, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/0043915739_10.jpg?resize=480%2C637&amp;ssl=1 480w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/><\/p><p><br \/>Un disco de arquitecturas complejas que no busca el camino f\u00e1cil, cuando el eco se apaga, sus frecuencias siguen dentro.<\/p><p><br \/><strong>Artist<\/strong>: Vegim<br \/><strong>Album<\/strong>: Magnetopause<br \/><strong>Label<\/strong>: TMM Recordings<br \/><strong>Date on stores<\/strong>: 25.03.2026<br \/><strong>Format<\/strong>: Vinyl + digital<br \/><strong>Produced<\/strong> by Vegim<br \/><strong>Mastering<\/strong> by Boris<br \/><strong>Artwork<\/strong> by Kobalt<\/p><h3><span style=\"font-size: 18px;\">LINKS<\/span><\/h3><p><strong>Soundcloud<\/strong><br \/><span style=\"text-decoration: underline;\"><a href=\"https:\/\/soundcloud.com\/tmmr\/vegim-magnetopause-ep-ltd075\">https:\/\/soundcloud.com\/tmmr\/vegim-magnetopause-ep-ltd075<\/a><\/span><\/p><p><br \/><strong>Bandcamp<\/strong><br \/><a href=\"https:\/\/tmmrecords.bandcamp.com\/album\/magnetopause\"><span style=\"text-decoration: underline;\">https:\/\/tmmrecords.bandcamp.com\/album\/magnetopause<\/span><\/a><\/p><p><br \/><strong>Instagram<\/strong><br \/><a href=\"https:\/\/www.instagram.com\/tmm_recordings\/\"><span style=\"text-decoration: underline;\">https:\/\/www.instagram.com\/tmm_recordings\/<\/span><\/a><br \/><a href=\"https:\/\/www.instagram.com\/vegim.hashimi\/\"><span style=\"text-decoration: underline;\">https:\/\/www.instagram.com\/vegim.hashimi\/<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c3b081 elementor-widget elementor-widget-text-editor\" data-id=\"4c3b081\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>#basspiritmagazine\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-36de48ad\" data-id=\"36de48ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c00ba48\" data-id=\"1c00ba48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18dcaf74 elementor-widget elementor-widget-spacer\" data-id=\"18dcaf74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bd29022 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4bd29022\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68147453 elementor-widget elementor-widget-text-editor\" data-id=\"68147453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cambiando la t\u00f3nica de comunicar por un Gin tonic.<\/p><p>\u00a0<\/p><p>Te invitamos a que nos visites en Instagram y si te gusta lo que ves&#8230;\u00a0\u00a0<\/p><p><strong>\u00a1 S\u00cdGUENOS !<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c2f63fe elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"7c2f63fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-34b2cf4\" href=\"https:\/\/www.instagram.com\/basspiritmag\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-582cd17b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"582cd17b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26abdb60 elementor-widget elementor-widget-spacer\" data-id=\"26abdb60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-443674ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"443674ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16b42fe4\" data-id=\"16b42fe4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Magnetopause EP de Vegim explora tensi\u00f3n, espacio y narrativa en el techno balc\u00e1nico, combinando inmersi\u00f3n sonora y funcionalidad en club<\/p>\n","protected":false},"author":3,"featured_media":6666,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,13],"tags":[],"class_list":["post-6652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basspiritmagazine","category-noticias"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/2.jpg?fit=2214%2C2214&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pbSsRh-1Ji","jetpack-related-posts":[{"id":6668,"url":"https:\/\/basspirit.com\/es\/2026\/04\/28\/cecilia-tosh-secrets-ep-denude-atmosfera-narrativa-y-precision-en-el-techno-contemporaneo\/","url_meta":{"origin":6652,"position":0},"title":"Cecilia Tosh \u2014 Secrets EP: atm\u00f3sfera y narrativa en el techno contempor\u00e1neo","author":"Paquitaplatos","date":"28 abril 2026","format":false,"excerpt":"Secrets EP de Cecilia Tosh en Denude explora techno atmosf\u00e9rico y emocional, combinando narrativa personal, tensi\u00f3n sonora y precisi\u00f3n de club desde Berl\u00edn.","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"denude records","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/denude-records.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/denude-records.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/denude-records.jpg?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/denude-records.jpg?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/denude-records.jpg?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6306,"url":"https:\/\/basspirit.com\/es\/2025\/09\/23\/tension-pulse-ep-ricardo-garduno-y-drucal-lanzan-nuevo-vinilo-en-loopaina-records\/","url_meta":{"origin":6652,"position":1},"title":"Tension Pulse EP: Ricardo Garduno y Drucal lanzan nuevo vinilo en Loopaina Records","author":"Jorge del R\u00edo","date":"23 septiembre 2025","format":false,"excerpt":"Tension Pulse EP es la cuarta referencia en vinilo de Loopaina Records. Ricardo Garduno y Drucal unen fuerzas en un lanzamiento de techno hipn\u00f3tico, groove y remezclas imprescindibles","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"RICARDO GARDUNO","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/09\/loopaina-records-1.png?fit=835%2C834&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/09\/loopaina-records-1.png?fit=835%2C834&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/09\/loopaina-records-1.png?fit=835%2C834&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/09\/loopaina-records-1.png?fit=835%2C834&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6618,"url":"https:\/\/basspirit.com\/es\/2026\/04\/14\/niels-orens-never-again-offc03-introspeccion-sonora-entre-alienacion-textura-y-tension-contenida\/","url_meta":{"origin":6652,"position":2},"title":"Niels Orens \u2013 Never Again: introspecci\u00f3n sonora entre textura y tensi\u00f3n contenida","author":"Paquitaplatos","date":"14 abril 2026","format":false,"excerpt":"Niels Orens lanza Never Again en Off Corner Records el 17 de abril de 2026, un EP que explora alienaci\u00f3n, textura y tensi\u00f3n","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"niels orens","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/a3390116066_10.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/a3390116066_10.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/a3390116066_10.jpg?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/a3390116066_10.jpg?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2026\/04\/a3390116066_10.jpg?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6126,"url":"https:\/\/basspirit.com\/es\/2025\/03\/06\/aizikovic-lanza-dry-blow-en-phase-imprint-con-un-remix-especial-de-comissar-lag\/","url_meta":{"origin":6652,"position":3},"title":"Aizikovic lanza \u00abDry Blow\u00bb en Phase Imprint con un remix especial de Comissar Lag","author":"Paquitaplatos","date":"6 marzo 2025","format":false,"excerpt":"\"Dry Blow\" de Aizikovic fusiona techno industrial y percusi\u00f3n hipn\u00f3tica en seis cortes intensos. Destaca un remix de Comissar Lag, elevando este EP a una pieza clave para los amantes del sonido underground","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"phase imprint","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/03\/0038694325_10.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/03\/0038694325_10.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/03\/0038694325_10.jpg?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/03\/0038694325_10.jpg?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/03\/0038694325_10.jpg?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6409,"url":"https:\/\/basspirit.com\/es\/2025\/11\/26\/canibal-ep-nwhr-y-el-instinto-que-devora-la-pista\/","url_meta":{"origin":6652,"position":4},"title":"Canibal EP: NWHR y el instinto que devora la pista","author":"Jorge del R\u00edo","date":"26 noviembre 2025","format":false,"excerpt":"El Canibal EP de NWHR explora un techno oscuro y visceral, con cuatro pistas que devoran la pista de baile. Este lanzamiento de Tempio Omega transforma la m\u00fasica en experiencia f\u00edsica","rel":"","context":"En \u00abart\u00edculos\u00bb","block_context":{"text":"art\u00edculos","link":"https:\/\/basspirit.com\/es\/category\/articulos\/"},"img":{"alt_text":"vinilo techno oscuro","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/11\/81C358FC-7086-4D7B-B422-DC89E1D9E6E8.jpeg?fit=1183%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/11\/81C358FC-7086-4D7B-B422-DC89E1D9E6E8.jpeg?fit=1183%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/11\/81C358FC-7086-4D7B-B422-DC89E1D9E6E8.jpeg?fit=1183%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/11\/81C358FC-7086-4D7B-B422-DC89E1D9E6E8.jpeg?fit=1183%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2025\/11\/81C358FC-7086-4D7B-B422-DC89E1D9E6E8.jpeg?fit=1183%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2688,"url":"https:\/\/basspirit.com\/es\/2022\/02\/02\/bastet-productor-techno\/","url_meta":{"origin":6652,"position":5},"title":"Bastet: el productor Techno revelaci\u00f3n de 2021 en Espa\u00f1a lanza su EP \u2018Oxigen\u2019","author":"Paquitaplatos","date":"2 febrero 2022","format":false,"excerpt":"Fran Bastet \u2014o simplemente Bastet, su nombre art\u00edstico oficil\u2014 es el productor musical m\u00e1s activo de la cultura Techno en Espa\u00f1a.","rel":"","context":"En \u00abbasspiritmagazine\u00bb","block_context":{"text":"basspiritmagazine","link":"https:\/\/basspirit.com\/es\/category\/basspiritmagazine\/"},"img":{"alt_text":"bastet productor techno","src":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2022\/02\/bastet_01-1.jpg?fit=591%2C590&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2022\/02\/bastet_01-1.jpg?fit=591%2C590&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/basspirit.com\/wp-content\/uploads\/2022\/02\/bastet_01-1.jpg?fit=591%2C590&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/posts\/6652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/comments?post=6652"}],"version-history":[{"count":5,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/posts\/6652\/revisions"}],"predecessor-version":[{"id":6661,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/posts\/6652\/revisions\/6661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/media\/6666"}],"wp:attachment":[{"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/media?parent=6652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/categories?post=6652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basspirit.com\/es\/wp-json\/wp\/v2\/tags?post=6652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}